{"id":900,"date":"2021-10-22T16:17:01","date_gmt":"2021-10-22T16:17:01","guid":{"rendered":"https:\/\/www.cpvenice.com\/ristorante-e-bar\/"},"modified":"2024-05-02T14:47:45","modified_gmt":"2024-05-02T14:47:45","slug":"restaurant-und-bar","status":"publish","type":"page","link":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/","title":{"rendered":"Restaurant und Bar"},"content":{"rendered":"<p>Was auch immer der Grund f\u00fcr Ihre Reise sein mag, verzichten Sie nicht auf Momente, die dem Genuss gewidmet sind: Unser Restaurant Il Campiello und unsere Bar Ca&#8216; D&#8217;Oro, die <strong>hauseigene Bar und das Restaurant<\/strong> unseres modernen <strong>4-Sterne-Hotels in Venedig &#8211; Quarto d&#8217;Altino<\/strong>, werden Sie auf eine Entdeckungsreise durch die Aromen der italienischen und venezianischen K\u00fcche mitnehmen.<\/p>\n<p>Die gastronomischen Einrichtungen des Hotels Crowne Plaza Venice East stehen Ihnen vom Aufwachen bis zum Schlafengehen zur Verf\u00fcgung. Morgens st\u00e4rken Sie sich an unserem <strong>reichhaltigen Fr\u00fchst\u00fcck mit Speisen f\u00fcr jeden Geschmack<\/strong>: s\u00fc\u00df, herzhaft, warm und kalt. Setzen Sie den Tag mit einem ausgezeichneten Kaffee oder einem Snack an unserer <strong>Bar<\/strong> fort und entdecken Sie zum Abschluss die Aromen der italienischen und venezianischen K\u00fcche in unserem <strong>Restaurant<\/strong>, das <strong>mittags im Bistro-Modus<\/strong> und <strong>abends<\/strong> mit <strong>komplettem Service<\/strong> ge\u00f6ffnet ist.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was auch immer der Grund f\u00fcr Ihre Reise sein mag, verzichten Sie nicht auf Momente, die dem Genuss gewidmet sind: Unser Restaurant Il Campiello und unsere Bar Ca&#8216; D&#8217;Oro, die hauseigene Bar und das Restaurant unseres modernen 4-Sterne-Hotels in Venedig &#8211; Quarto d&#8217;Altino, werden Sie auf eine Entdeckungsreise durch die Aromen der italienischen und venezianischen [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"parent":0,"menu_order":50,"comment_status":"closed","ping_status":"closed","template":"template-restaurants.php","meta":{"footnotes":""},"class_list":["post-900","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bar und Restaurant hauseigen | Crowne Plaza Venice<\/title>\n<meta name=\"description\" content=\"Entspannung in der eleganten und ger\u00e4umigen Bar oder im innovativen Restaurant, wo die traditionelle K\u00fcche mit ausgefallenen Kreationen unseres K\u00fcchenchefs vereint wird.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bar und Restaurant hauseigen | Crowne Plaza Venice\" \/>\n<meta property=\"og:description\" content=\"Entspannung in der eleganten und ger\u00e4umigen Bar oder im innovativen Restaurant, wo die traditionelle K\u00fcche mit ausgefallenen Kreationen unseres K\u00fcchenchefs vereint wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/\" \/>\n<meta property=\"og:site_name\" content=\"Crowne Plaza Venice East\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T14:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cpvenice.com\/wp-content\/uploads\/sites\/365\/2021\/12\/Crowne-Plaza-Venice-East-Rooms-Standard-Room-King-Accessible-bed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/\",\"url\":\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/\",\"name\":\"Bar und Restaurant hauseigen | Crowne Plaza Venice\",\"isPartOf\":{\"@id\":\"https:\/\/www.cpvenice.com\/de\/#website\"},\"datePublished\":\"2021-10-22T16:17:01+00:00\",\"dateModified\":\"2024-05-02T14:47:45+00:00\",\"description\":\"Entspannung in der eleganten und ger\u00e4umigen Bar oder im innovativen Restaurant, wo die traditionelle K\u00fcche mit ausgefallenen Kreationen unseres K\u00fcchenchefs vereint wird.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cpvenice.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurant und Bar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cpvenice.com\/de\/#website\",\"url\":\"https:\/\/www.cpvenice.com\/de\/\",\"name\":\"Crowne Plaza Venice East\",\"description\":\"Just another ms.decms.eu site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cpvenice.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bar und Restaurant hauseigen | Crowne Plaza Venice","description":"Entspannung in der eleganten und ger\u00e4umigen Bar oder im innovativen Restaurant, wo die traditionelle K\u00fcche mit ausgefallenen Kreationen unseres K\u00fcchenchefs vereint wird.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/","og_locale":"de_DE","og_type":"article","og_title":"Bar und Restaurant hauseigen | Crowne Plaza Venice","og_description":"Entspannung in der eleganten und ger\u00e4umigen Bar oder im innovativen Restaurant, wo die traditionelle K\u00fcche mit ausgefallenen Kreationen unseres K\u00fcchenchefs vereint wird.","og_url":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/","og_site_name":"Crowne Plaza Venice East","article_modified_time":"2024-05-02T14:47:45+00:00","og_image":[{"width":2200,"height":1200,"url":"https:\/\/www.cpvenice.com\/wp-content\/uploads\/sites\/365\/2021\/12\/Crowne-Plaza-Venice-East-Rooms-Standard-Room-King-Accessible-bed.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/","url":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/","name":"Bar und Restaurant hauseigen | Crowne Plaza Venice","isPartOf":{"@id":"https:\/\/www.cpvenice.com\/de\/#website"},"datePublished":"2021-10-22T16:17:01+00:00","dateModified":"2024-05-02T14:47:45+00:00","description":"Entspannung in der eleganten und ger\u00e4umigen Bar oder im innovativen Restaurant, wo die traditionelle K\u00fcche mit ausgefallenen Kreationen unseres K\u00fcchenchefs vereint wird.","breadcrumb":{"@id":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cpvenice.com\/de\/restaurant-und-bar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cpvenice.com\/de\/"},{"@type":"ListItem","position":2,"name":"Restaurant und Bar"}]},{"@type":"WebSite","@id":"https:\/\/www.cpvenice.com\/de\/#website","url":"https:\/\/www.cpvenice.com\/de\/","name":"Crowne Plaza Venice East","description":"Just another ms.decms.eu site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cpvenice.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/pages\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":0,"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/pages\/900\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cpvenice.com\/de\/wp-json\/wp\/v2\/media?parent=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}